{"id":442,"date":"2024-09-16T18:14:01","date_gmt":"2024-09-16T18:14:01","guid":{"rendered":"https:\/\/www.2000m2.eu\/?post_type=crop&#038;p=442"},"modified":"2026-03-24T06:21:49","modified_gmt":"2026-03-24T06:21:49","slug":"raps","status":"publish","type":"crop","link":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/","title":{"rendered":"Raps"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Raps, Brassica napus<\/h1>\n\n\n\n<p><\/p>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box442_681c6c-ba .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-link-wrap{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;background:var(--accent);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box442_681c6c-ba.wp-block-kadence-infobox{max-width:100%;}.kt-info-box442_681c6c-ba .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box442_681c6c-ba .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:1920px;height:0px;max-width:100%;}.kt-info-box442_681c6c-ba .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box442_681c6c-ba .kt-info-svg-icon-flip, .kt-info-box442_681c6c-ba .kt-blocks-info-box-number{font-size:25px;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-media{color:var(--accent-3);background:var(--accent-4);border-color:#444444;border-radius:167px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:11px;padding-right:11px;padding-bottom:11px;padding-left:11px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:167px;}.kt-info-box442_681c6c-ba .kt-infobox-textcontent .kt-blocks-info-box-text{color:#ffffff;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:#ffffff;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 767px){.kt-info-box442_681c6c-ba .kt-blocks-info-box-link-wrap{text-align:left;display:block;}.kt-info-box442_681c6c-ba .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box442_681c6c-ba\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg\" alt=\"\" width=\"1920\" height=\"1358\" class=\"kt-info-box-image wp-image-807\" srcset=\"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg 1920w, https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1-300x212.jpg 300w, https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1-768x543.jpg 768w, https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1-1024x724.jpg 1024w, https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1-1536x1086.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Fl\u00e4che global<\/strong>: 39,8 Millionen Hektar<br><strong>Fl\u00e4che auf dem Weltacker<\/strong>: 43,6 m\u00b2 (2,2 %)<br><strong>Herkunftsregion<\/strong>: Indien<br><strong>Hauptanbaugebiete<\/strong>: Kanada, Indien, China<br><strong>Verwendung \/ Hauptnutzen<\/strong>: Speise\u00f6l, Agrarsprit, Tierfutter<\/p><\/div><\/span><\/div>\n\n\n\n<p>Wirtschaftlich hat Raps heutzutage eine gro\u00dfe Bedeutung auf dem globalen Agrarmarkt. Dabei ist Raps eine junge Kulturpflanze. \u00dcber Jahrhunderte wurde er wild gepfl\u00fcckt, bevor er erst ab dem 17. Jahrhundert in Mitteleuropa auf \u00c4ckern kultiviert wurde, um aus den Samen \u00d6l f\u00fcr Lampen zu gewinnen. Die Wissenschaft vermutet, dass Raps aus einer Kreuzung zwischen dem Wilden Gem\u00fcsekohl (<em>Brassica oleracea<\/em>) und R\u00fcbsen (<em>Brassica rapa<\/em>) im Mittelmeerraum entstanden ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gelbe Bl\u00fctenpracht mit hohen Anspr\u00fcchen<\/h2>\n\n\n\n<p>Raps geh\u00f6rt zur Familie der Kreuzbl\u00fctengew\u00e4chsen und ist mit R\u00fcbe und Kohl verwandt. Er ist eine einj\u00e4hrige Krautpflanze mit einem aufrechten, verzweigten St\u00e4ngel, der bis zu zwei Meter hoch werden kann. Die Rapspflanze ist von grau-blauer Farbe und bildet unter der Erde eine Pfahlwurzel aus. In Rapsanbaugebieten entz\u00fcckt die Kultur vor allem durch das dichte gelbe Bl\u00fctenmeer w\u00e4hrend der Bl\u00fchzeit der Pflanzen. Die Felder sehen so prachtvoll aus, da jede Pflanze zwanzig bis sechzig Bl\u00fcten tr\u00e4gt. Diese zwittrigen Bl\u00fcten sind in Trauben angeordnet. Die Knospen einer solchen Traube bl\u00fchen von unten nach oben nacheinander auf. So entz\u00fcckt eine Rapspflanze je nach Witterung ganze drei bis f\u00fcnf Wochen ihre Betrachter mit ihrer Bl\u00fctenpracht, auch wenn jede einzelne Bl\u00fcte nur ein bis zwei Tage offen ist. Doch nur etwa die H\u00e4lfte der Bl\u00fcten bildet Schoten aus \u2013 mehr w\u00fcrde die Pflanze wohl nicht versorgen k\u00f6nnen. Aber auch die Insekten schaffen nicht all die Bl\u00fcten zu befruchten und auf diese Fremdbefruchtung ist der Raps angewiesen. In den Schoten wachsen die dunkelbraun-schw\u00e4rzlichen runden Samen. Sie haben einen Durchmesser von 1,5 bis 2,5 Millimeter und bleiben sehr lange keimf\u00e4hig. Rapssaat im Boden kann nach bis zu zehn Jahren noch keimen und damit auch Nachfr\u00fcchte st\u00f6ren.<br><\/p>\n\n\n\n<p>Die Anspr\u00fcche an den Boden der Rapspflanze sind \u00e4hnlich wie die des Weizens. Beide Kulturen ben\u00f6tigen tiefgr\u00fcndigen Boden und m\u00f6gen keine Staun\u00e4sse. Auch leichte oder flachgr\u00fcndige B\u00f6den, die rasch austrocknen, verringern die Ertragssicherheit des Rapses und sind daher weniger geeignet. Raps stellt hohe Anspr\u00fcche bez\u00fcglich der N\u00e4hrstoffversorgung, er braucht zum Beispiel deutlich mehr Stickstoff als Getreide.<\/p>\n\n\n\n<p>Raps sollte nicht mehrere Jahre hintereinander auf dem gleichen Feld angebaut werden, da sonst spezifische Krankheiten und Rapssch\u00e4dlinge \u00fcberhandnehmen k\u00f6nnen. Daher ist Raps auf die Fruchtfolge mit anderen Ackerkulturen angewiesen. Weizen und anderes Getreide mit \u00e4hnlichen Bodenanspr\u00fcchen eignen sich besonders gut und profitieren gleichzeitig sehr von einer Raps-Zwischenfrucht. Denn bei der Rapsernte bleiben meistens die abgeernteten Pflanzenteile und Wurzeln auf dem Feld, was die Humusbildung, die Bodenstruktur und die biologische Aktivit\u00e4t des Bodens f\u00f6rdert, woraus die Getreidekulturen in der Fruchtfolge ebenfalls Vorteile ziehen. Zudem durchwurzelt Sommerraps den Boden stark und sorgt damit f\u00fcr eine gute Bodendurchl\u00fcftung. So ist Raps als Zwischenfrucht von Getreide insbesondere in Europa sehr beliebt geworden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vom wilden Raps zu genver\u00e4ndertem Gro\u00dfanbau<\/h2>\n\n\n\n<p>Erste Hinweise f\u00fcr die Verwendung von Raps stammen von 2000 vor unserer Zeit aus Indien \u2013 hier wurde die Pflanze zur \u00d6lgewinnung, in der Medizin und als Nahrungsmittel genutzt. In Mitteleuropa wurde Raps lange wild gesammelt, aber erst ab dem 17. Jahrhundert im gr\u00f6\u00dferen Stil angebaut \u2013 anfangs haupts\u00e4chlich als wichtiger Brennstoff f\u00fcr \u00d6llampen. Wegen des bitteren Geschmacks (durch einen hohen Gehalt an Erucas\u00e4ure) wurde Raps\u00f6l nur eingeschr\u00e4nkt als Speise\u00f6l verwendet, zum Beispiel in Hungerzeiten. In der zweiten H\u00e4lfte des 19. Jahrhunderts brach die Rapsproduktion in Europa stark ein, da billigere Erd\u00f6limporte und tropische Speise\u00f6le auf den Markt kamen. Dies \u00e4nderte sich erst Mitte der 1970er Jahre wieder. Damals kamen Neuz\u00fcchtungen mit zwei neuen Merkmalen auf den Markt: Das \u00d6l aus diesem sogenannten 00-Raps (&#8222;Doppel-Null&#8220;) enth\u00e4lt nur noch geringe Mengen der bitter schmeckenden Erucas\u00e4ure und ist nahezu frei von Senf\u00f6lglykosiden. Ohne diese giftigen Stoffe kann das \u00d6l nun als Lebensmittel oder Tierfutter verwendet werden.<\/p>\n\n\n\n<p>Raps wird heute weltweit in den wintermilden Gebieten der gem\u00e4\u00dfigten Klimaregionen angebaut. Hauptanbaugebiete sind Kanada, Indien und China, aber auch in Europa ist Raps ein wichtiger Bestandteil der Landwirtschaft. In Kanada, dem weltweit wichtigsten Rapsproduzenten, wird haupts\u00e4chlich Sommerraps angebaut. Nicht so in Mitteleuropa \u2013 dort ist es meistens Winterraps. Dieser wird im Herbst ausges\u00e4t und im darauffolgenden Fr\u00fchsommer geerntet. Winter- wie Sommerraps werden haupts\u00e4chlich f\u00fcr die \u00d6lgewinnung verwendet, daneben gibt es auch blattreiche Rapssorten, die als Futterraps angebaut werden.<\/p>\n\n\n\n<p>Leider gibt es auch einige Probleme, die durch den gro\u00dffl\u00e4chigen Anbau von Raps entstehen. Durch die Anbaumethode der Monokultur werden andere, einheimische Pflanzenarten verdr\u00e4ngt und unterdr\u00fcckt, es kommt zu einem R\u00fcckgang der Biodiversit\u00e4t. Auch die Vielfalt der Insekten und anderen Tiere geht zur\u00fcck, da das \u00d6kosystem gest\u00f6rt wird. Dieser Prozess wird versch\u00e4rft durch die Verwendung von genmanipulierten Rapssorten die immun gegen Herbizide (Pflanzenschutzmittel), Insektizide (Insektenschutzmittel) und Fungizide (Schutzmittel gegen Pilze) sind. Wenn nun gro\u00dffl\u00e4chig diese Mittel auf den Rapsfeldern verteilt werden, sterben alle Pflanzen auf und neben dem Acker ab, mit Ausnahme der Rapspflanzen. Kaum eine Kulturpflanze verbreitet sich so schnell und leicht wie der Raps. Der Pollen fliegt meist kilometerweit. So gelangen die genmanipulierten Rapspollen auch in Gebiete, in denen genmanipulierte Pflanzen verboten oder nur beschr\u00e4nkt sind, Naturschutzgebiete und Landschaftsschutzgebiete. Die Folge: Auch hier f\u00e4ngt der ver\u00e4nderte Raps an zu wachsen und sich zu verbreiten. Infolgedessen kommt es hier ebenso zu einem R\u00fcckgang der Biodiversit\u00e4t. \u201eSollte in Zukunft nicht darauf geachtet werden, dass genmanipulierte Sorten und urspr\u00fcngliche Sorten voneinander getrennt kultiviert werden, wird es bald keine M\u00f6glichkeit geben sie wieder aus der Umwelt zu entfernen\u201c, warnen Expert:innen. Weltweit lag der GVO-Anteil im Rapsanbau 2019 bei 27 Prozent, wovon der gr\u00f6\u00dfte Teil auf Kanada fiel, wo 95 Prozent des Rapses genver\u00e4ndert sind. Gr\u00f6\u00dfter Raps-Exporteur ist Kanada (Roh\u00f6l\/Rapskuchen\/Rapsssaat) und der gr\u00f6\u00dfte Importeur sowohl mengen- wie umsatzm\u00e4\u00dfig sind die USA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Futter f\u00fcr Mensch, Tier, Tank und Industrie<\/h2>\n\n\n\n<p>Wir Menschen essen Raps meistens in Form von Speise\u00f6l oder Margarine. Das \u00d6l gilt als gesund, da es ein besonders gutes Verh\u00e4ltnis der beiden f\u00fcr den K\u00f6rper wichtigen mehrfach unges\u00e4ttigten Fetts\u00e4uren Omega-3 und Omega-6 hat. Raffiniertes Raps\u00f6l ist geschmacksneutral und wird, auch wegen seines hohen Rauchpunkts, gerne zum Frittieren und Braten oder auch in Mayonnaise und Dressings genutzt. Natives Raps\u00f6l hat hingegen eine nussige Note. Neben der Nutzung als \u00d6l, wird Raps in manchen Regionen aber auch als Blattgem\u00fcse verspeist &#8211; insbesondere in Simbabwe und anderen L\u00e4ndern des s\u00fcdlichen Afrikas werden daf\u00fcr spezielle Rapssorten kultiviert.<\/p>\n\n\n\n<p>Aber nicht nur wir Menschen essen Raps und \u00d6l. Auch als Tierfutter wird es eingesetzt \u2013 insbesondere die Pressr\u00fcckst\u00e4nde, die als Nebenprodukt bei der Herstellung des \u00d6ls entstehen. Dieser Rapsschrot oder Rapskuchen ist sehr eiwei\u00dfreich und eignet sich daher gut als Futtermittel. Ein weiterer wichtiger Einsatzbereich von Raps ist Biodiesel: In Europa wird Biodiesel sogar \u00fcberwiegend aus Raps\u00f6l gewonnen. In Deutschland zum Beispiel wird die H\u00e4lfte des gewonnenen Raps\u00f6ls als Pflanzenkraftstoff oder Biodiesel verwendet. Raps wird zudem f\u00fcr spezielle \u00d6le, Fette und andere Industriechemikalien genutzt oder auch in Form von biologisch abbaubaren \u00d6len und Schmierstoffen als Grundstoff bei der Herstellung von Farben und Lacke sowie f\u00fcr Weichmacher und Tenside eingesetzt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Absolutes Bienenparadies, aber kaum Bio-Anbau<\/h2>\n\n\n\n<p>Raps ist eine insektenfreundliche Pflanze und daher sehr bedeutend f\u00fcr die Imkerei. In Deutschland sind Rapsbl\u00fcten eine der wichtigsten Nektarquellen f\u00fcr Honigbienen. Aus einem Hektar Raps k\u00f6nnen Bienen in einer Saison bis zu 494 kg Honig produzieren. Weil Raps sehr viel Stickstoff ben\u00f6tigt und leicht von Sch\u00e4dlingen befallen wird, gibt es bis heute kaum Bio-Raps. Durch das Verbot von Neonicotinoiden als Pflanzenschutzmittel im EU-Raum gibt es aber verschiedene Forschungsprojekte f\u00fcr den biologischen Rapsanbau. Experimente mit Untersaaten, fr\u00fcheren Aussaat-Terminen oder der gezielten F\u00f6rderung von N\u00fctzlingen lassen hoffen, dass es in Zukunft m\u00f6glich sein wird, gr\u00f6\u00dfere Mengen an Raps in besserem Einklang mit der Natur zu produzieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quellen<\/h2>\n\n\n\n<p>Svotwa &amp; Katsaruware (2018): Performance of Two Rape (<em>Brassica napus<\/em>) Cultivars under Different Fertilizer Management Levels in the Smallholder Sector of Zimbabwe. <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/10.1155\/2018\/2351204\">Link<\/a>. <br>Utopia.de: Raps\u00f6l bei \u00d6ko-Test: 12 sind \u201esehr gut\u201c \u2013 aber in fast allen stecken Pestizide und Mineral\u00f6l. <a href=\"https:\/\/utopia.de\/ratgeber\/rapsoel-bei-oekotest-sehr-gut-aber-in-fast-allen-stecken-pestizide-und-mineraloel_712150\/\">Link<\/a>. <br>Utopia.de: Rapswachs: Veganes Wachs ohne Paraffin. <a href=\"https:\/\/utopia.de\/ratgeber\/rapswachs-veganes-wachs-ohne-paraffin_293540\/\">Link<\/a>. <br>International Society for Horticultural Science: Importance and development of rape (brassica napus l.) as a vegetable in Zambia. <a href=\"https:\/\/www.ishs.org\/ishs-article\/153_22\">Link<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raps, Brassica napus Wirtschaftlich hat Raps heutzutage eine gro\u00dfe Bedeutung auf dem globalen Agrarmarkt. Dabei ist Raps eine junge Kulturpflanze. \u00dcber Jahrhunderte wurde er wild gepfl\u00fcckt, bevor er erst ab dem 17. Jahrhundert in Mitteleuropa auf \u00c4ckern kultiviert wurde, um aus den Samen \u00d6l f\u00fcr Lampen zu gewinnen. Die Wissenschaft vermutet, dass Raps aus einer&#8230;<\/p>\n","protected":false},"featured_media":807,"parent":0,"menu_order":124,"template":"","tags":[],"crops":[17],"class_list":["post-442","crop","type-crop","status-publish","has-post-thumbnail","hentry","crops-oelfruechte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raps - 2000m2<\/title>\n<meta name=\"description\" content=\"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raps - 2000m2\" \/>\n<meta property=\"og:description\" content=\"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/\" \/>\n<meta property=\"og:site_name\" content=\"2000m2\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T06:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1358\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/\",\"url\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/\",\"name\":\"Raps - 2000m2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.2000m2.eu\\\/wp-content\\\/uploads\\\/Raps_300dpi-1.jpg\",\"datePublished\":\"2024-09-16T18:14:01+00:00\",\"dateModified\":\"2026-03-24T06:21:49+00:00\",\"description\":\"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.2000m2.eu\\\/wp-content\\\/uploads\\\/Raps_300dpi-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.2000m2.eu\\\/wp-content\\\/uploads\\\/Raps_300dpi-1.jpg\",\"width\":1920,\"height\":1358},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/kultur\\\/raps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/\",\"name\":\"2000m2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#organization\",\"name\":\"2000m2\",\"url\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.2000m2.eu\\\/wp-content\\\/uploads\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.2000m2.eu\\\/wp-content\\\/uploads\\\/logo.png\",\"width\":445,\"height\":140,\"caption\":\"2000m2\"},\"image\":{\"@id\":\"https:\\\/\\\/www.2000m2.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raps - 2000m2","description":"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/","og_locale":"de_DE","og_type":"article","og_title":"Raps - 2000m2","og_description":"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,","og_url":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/","og_site_name":"2000m2","article_modified_time":"2026-03-24T06:21:49+00:00","og_image":[{"width":1920,"height":1358,"url":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/","url":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/","name":"Raps - 2000m2","isPartOf":{"@id":"https:\/\/www.2000m2.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/#primaryimage"},"image":{"@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg","datePublished":"2024-09-16T18:14:01+00:00","dateModified":"2026-03-24T06:21:49+00:00","description":"Raps, Brassica napus Fl\u00e4che global: 39,8 Millionen HektarFl\u00e4che auf dem Weltacker: 43,6 m\u00b2 (2,2 %)Herkunftsregion: IndienHauptanbaugebiete: Kanada,","breadcrumb":{"@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.2000m2.eu\/de\/kultur\/raps\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/#primaryimage","url":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg","contentUrl":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/Raps_300dpi-1.jpg","width":1920,"height":1358},{"@type":"BreadcrumbList","@id":"https:\/\/www.2000m2.eu\/de\/kultur\/raps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.2000m2.eu\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Raps"}]},{"@type":"WebSite","@id":"https:\/\/www.2000m2.eu\/de\/#website","url":"https:\/\/www.2000m2.eu\/de\/","name":"2000m2","description":"","publisher":{"@id":"https:\/\/www.2000m2.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.2000m2.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.2000m2.eu\/de\/#organization","name":"2000m2","url":"https:\/\/www.2000m2.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.2000m2.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/logo.png","contentUrl":"https:\/\/www.2000m2.eu\/wp-content\/uploads\/logo.png","width":445,"height":140,"caption":"2000m2"},"image":{"@id":"https:\/\/www.2000m2.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/crop\/442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/crop"}],"about":[{"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/types\/crop"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/media\/807"}],"wp:attachment":[{"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/media?parent=442"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/tags?post=442"},{"taxonomy":"crops","embeddable":true,"href":"https:\/\/www.2000m2.eu\/de\/wp-json\/wp\/v2\/crops?post=442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}